{"id":6666,"date":"2023-10-16T20:10:25","date_gmt":"2023-10-16T12:10:25","guid":{"rendered":"https:\/\/www.dcl-controls.com\/?p=6666"},"modified":"2025-04-15T22:46:09","modified_gmt":"2025-04-15T14:46:09","slug":"miconex-31th-2023","status":"publish","type":"post","link":"https:\/\/www.dcl-controls.com\/pt_pt\/solutions\/news\/miconex-31th-2023","title":{"rendered":"DCL Wuhan DCL Controls participou no dia 31 de China Internacional de Controle de Medi\u00e7\u00e3o e Instrumenta\u00e7\u00e3o de Exposi\u00e7\u00e3o em 2023"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"6666\" class=\"elementor elementor-6666\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41698a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41698a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d87417f\" data-id=\"d87417f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d674352 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"d674352\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">DCL Wuhan DCL Controls participou no dia 31 de China Internacional de Controle de Medi\u00e7\u00e3o e Instrumenta\u00e7\u00e3o de Exposi\u00e7\u00e3o em 2023<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5b7286 elementor-widget elementor-widget-post-info\" data-id=\"e5b7286\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-f77a2b5 elementor-inline-item\" itemprop=\"author\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.dcl-controls.com\/pt_pt\/author\/admin\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-user-circle\" viewbox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 104c-53 0-96 43-96 96s43 96 96 96 96-43 96-96-43-96-96-96zm0 144c-26.5 0-48-21.5-48-48s21.5-48 48-48 48 21.5 48 48-21.5 48-48 48zm0-240C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm0 448c-49.7 0-95.1-18.3-130.1-48.4 14.9-23 40.4-38.6 69.6-39.5 20.8 6.4 40.6 9.6 60.5 9.6s39.7-3.1 60.5-9.6c29.2 1 54.7 16.5 69.6 39.5-35 30.1-80.4 48.4-130.1 48.4zm162.7-84.1c-24.4-31.4-62.1-51.9-105.1-51.9-10.2 0-26 9.6-57.6 9.6-31.5 0-47.4-9.6-57.6-9.6-42.9 0-80.6 20.5-105.1 51.9C61.9 339.2 48 299.2 48 256c0-110.3 89.7-200 200-200s200 89.7 200 200c0 43.2-13.9 83.2-37.3 115.9z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tDCL Controls\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0d4ff16 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.dcl-controls.com\/pt_pt\/2023\/10\/16\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-calendar\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 192h424c6.6 0 12 5.4 12 12v260c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V204c0-6.6 5.4-12 12-12zm436-44v-36c0-26.5-21.5-48-48-48h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v36c0 6.6 5.4 12 12 12h424c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>Outubro 16, 2023<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-6e2633a elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-time\">\n\t\t\t\t\t\t\t\t\t\t<time>8:10 pm<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4425ee elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c4425ee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-592bf2f\" data-id=\"592bf2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d2988c elementor-widget elementor-widget-text-editor\" data-id=\"2d2988c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DCL Wuhan DCL Controls ir\u00e1 participar no dia 31 de China Internacional de Medi\u00e7\u00e3o, Controle e Instrumenta\u00e7\u00e3o de Exposi\u00e7\u00e3o em 2023 para fornecer a ind\u00fastria com atuadores el\u00e9tricos, v\u00e1lvulas el\u00e9tricas e aplica\u00e7\u00f5es estendido de atuadores el\u00e9tricos (Internet das Coisas).<\/p><p>Todos os especialistas da ind\u00fastria est\u00e3o cordialmente convidados a visitar e guia!<\/p><p>Data: 2023\/10\/23~2023\/10\/25<\/p><p>Endere\u00e7o: National Convention Center Em Pequim<\/p><p>Estande N\u00ba.: A511<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46e5426 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"46e5426\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d741684\" data-id=\"d741684\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56c855a elementor-widget elementor-widget-image\" data-id=\"56c855a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"792\" height=\"537\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/news\/images\/national-meeting-center.webp\" class=\"attachment-full size-full wp-image-6668\" alt=\"\u56fd\u5bb6\u4f1a\u8bae\u4e2d\u5fc3\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/news\/images\/national-meeting-center.webp 792w, https:\/\/www.dcl-controls.com\/content\/dam\/news\/images\/national-meeting-center-18x12.webp 18w\" sizes=\"(max-width: 792px) 100vw, 792px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9e9f068\" data-id=\"9e9f068\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-806ba47 elementor-widget elementor-widget-image\" data-id=\"806ba47\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"135\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/news\/images\/miconex.webp\" class=\"attachment-full size-full wp-image-6667\" alt=\"\u4e2d\u56fd\u56fd\u9645\u6d4b\u91cf\u63a7\u5236\u4e0e\u4eea\u5668\u4eea\u8868\u5c55\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/news\/images\/miconex.webp 800w, https:\/\/www.dcl-controls.com\/content\/dam\/news\/images\/miconex-18x3.webp 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9111ab elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a9111ab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"696\" height=\"600\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/home\/images\/shelf-banner\/dcl-actuator-product-line.webp\" class=\"attachment-full size-full wp-image-4829\" alt=\"DCL \u534e\u6613\u667a\u63a7 \u6267\u884c\u5668 \u4ea7\u54c1\u7ebf | DCL Actuators\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/home\/images\/shelf-banner\/dcl-actuator-product-line.webp 696w, https:\/\/www.dcl-controls.com\/content\/dam\/home\/images\/shelf-banner\/dcl-actuator-product-line-300x259.webp 300w, https:\/\/www.dcl-controls.com\/content\/dam\/home\/images\/shelf-banner\/dcl-actuator-product-line-14x12.webp 14w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2248d5 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c2248d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1dff5b2\" data-id=\"1dff5b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47bef13 elementor-widget elementor-widget-heading\" data-id=\"47bef13\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A fun\u00e7\u00e3o de Wuhan DCL Controls DCL atuador el\u00e9trico<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb95c39 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bb95c39\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-61e8ff5\" data-id=\"61e8ff5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f20ed25 elementor-widget elementor-widget-image\" data-id=\"f20ed25\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"422\" height=\"388\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/downloads\/user-manual\/vale-closed.webp\" class=\"attachment-full size-full wp-image-6112\" alt=\"\u7535\u52a8\u9600\u95e8\u5173\u95ed\u793a\u610f\u56fe\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/downloads\/user-manual\/vale-closed.webp 422w, https:\/\/www.dcl-controls.com\/content\/dam\/downloads\/user-manual\/vale-closed-13x12.webp 13w\" sizes=\"(max-width: 422px) 100vw, 422px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3a3b176\" data-id=\"3a3b176\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5a00e8 elementor-widget elementor-widget-image\" data-id=\"d5a00e8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"487\" height=\"378\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/tech\/images\/vale-opening.webp\" class=\"attachment-full size-full wp-image-6119\" alt=\"DCL\u6267\u884c\u5668\u5f00\u5ea6\u8c03\u8282\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/tech\/images\/vale-opening.webp 487w, https:\/\/www.dcl-controls.com\/content\/dam\/tech\/images\/vale-opening-15x12.webp 15w\" sizes=\"(max-width: 487px) 100vw, 487px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d41e5e5\" data-id=\"d41e5e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-266c8fe elementor-widget elementor-widget-image\" data-id=\"266c8fe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"466\" height=\"388\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/downloads\/user-manual\/vale-open.webp\" class=\"attachment-full size-full wp-image-6114\" alt=\"\u7535\u52a8\u9600\u95e8\u5168\u5f00\u793a\u610f\u56fe\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/downloads\/user-manual\/vale-open.webp 466w, https:\/\/www.dcl-controls.com\/content\/dam\/downloads\/user-manual\/vale-open-14x12.webp 14w\" sizes=\"(max-width: 466px) 100vw, 466px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12cf05d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"12cf05d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-524039a\" data-id=\"524039a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f2324a elementor-widget elementor-widget-image\" data-id=\"2f2324a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"936\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/tech\/images\/actuator-iot-application.webp\" class=\"attachment-full size-full wp-image-6132\" alt=\"DCL\u6267\u884c\u5668 \u7269\u8054\u7f51\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/tech\/images\/actuator-iot-application.webp 1142w, https:\/\/www.dcl-controls.com\/content\/dam\/tech\/images\/actuator-iot-application-15x12.webp 15w\" sizes=\"(max-width: 1142px) 100vw, 1142px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14a7f8f elementor-widget elementor-widget-image\" data-id=\"14a7f8f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/actuator\/images\/iot\/actuator-valve-in-iot.gif\" class=\"attachment-full size-full wp-image-5446\" alt=\"\u63a5\u5165\u7269\u8054\u7f51\u7684\u7535\u52a8\u9600\u95e8 | Electrical Actuator Valve in Iot\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/actuator\/images\/iot\/actuator-valve-in-iot.gif 1920w, https:\/\/www.dcl-controls.com\/content\/dam\/actuator\/images\/iot\/actuator-valve-in-iot-1536x864.gif 1536w, https:\/\/www.dcl-controls.com\/content\/dam\/actuator\/images\/iot\/actuator-valve-in-iot-18x10.gif 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a475a3b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a475a3b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f3a9f4e\" data-id=\"f3a9f4e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-312552a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"312552a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9579e8 elementor-widget elementor-widget-text-editor\" data-id=\"b9579e8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"http:\/\/www.miconex.com.cn\/\" rel=\"nofollow noopener\" target=\"_blank\"><em><span style=\"text-decoration: underline;\">Aprender sobre a China Internacional de Controle de Medi\u00e7\u00e3o e Instrumenta\u00e7\u00e3o de Exposi\u00e7\u00e3o (anteriormente, a Multinacional de Instrumenta\u00e7\u00e3o de Exposi\u00e7\u00f5es)<\/span><\/em><\/a><\/p><p><strong>Informa\u00e7\u00f5es b\u00e1sicas<\/strong><\/p><p>Miconex desenvolvimento da hist\u00f3ria<br \/>1. Fundado pela primeira-m\u00e3o, ele come\u00e7ou em 1983.<br \/>A inten\u00e7\u00e3o original de exposi\u00e7\u00e3o: acad\u00eamica Internacional confer\u00eancia + prot\u00f3tipo de exposi\u00e7\u00f5es<br \/>Nome: China Internacional de Controle de Medi\u00e7\u00e3o e Instrumenta\u00e7\u00e3o de Exposi\u00e7\u00e3o (anteriormente Multinacional de Instrumenta\u00e7\u00e3o de Exposi\u00e7\u00f5es)<br \/>Ingl\u00eas: Multinacional de Instrumenta\u00e7\u00e3o de Confer\u00eancias e de Exposi\u00e7\u00f5es<br \/>Abreviatura: Miconex<br \/>Organizador: China Sociedade de Instrumenta\u00e7\u00e3o<br \/>Miconex estreou no Centro de Exposi\u00e7\u00f5es de Xangai, em abril de 1983. Porque come\u00e7ou nos primeiros dias de &#034;reforma e abertura&#034;, que causou sensa\u00e7\u00e3o no mercado de conven\u00e7\u00f5es e exposi\u00e7\u00f5es da ind\u00fastria. Naquela \u00e9poca, mais de 400 expositores de 17 pa\u00edses e regi\u00f5es participaram da exposi\u00e7\u00e3o, com uma \u00e1rea de exposi\u00e7\u00e3o de apenas 17.000 metros quadrados, dos quais 80% foram expositores internacionais, incluindo 6 pavilh\u00f5es estrangeiros, mais de 2.000 estrangeiros relacionados com os expositores e mais de 300 representantes de confer\u00eancias acad\u00eamicas, incluindo cerca de 200 representantes estrangeiros, e mais de 300 programas de interc\u00e2mbio t\u00e9cnico.. O &#034;Multinacionais de Instrumenta\u00e7\u00e3o Exposi\u00e7\u00e3o&#034; tornou-se o primeiro &#034;alternativa&#034; de exposi\u00e7\u00e3o (especialmente aprovados pelo Conselho de Estado) n\u00e3o \u00e9 hospedado pelo &#034;Conselho chin\u00eas para a Promo\u00e7\u00e3o do Com\u00e9rcio&#034; (CCPIT) na China na \u00e9poca. Desde ent\u00e3o, as comportas da China ind\u00fastria de conven\u00e7\u00f5es e feiras abriu abruptamente com o som da buzina de &#034;reforma e abertura&#034;. V\u00e1rios &#034;her\u00f3is&#034; (exposi\u00e7\u00e3o organizadores) seguiram um ap\u00f3s o outro, e pol\u00edticas locais foram gradualmente &#034;soltos&#034;, inaugurando a primeira onda de desenvolvimento de conven\u00e7\u00f5es e exposi\u00e7\u00f5es da ind\u00fastria no meu pa\u00eds no final da d\u00e9cada de 1980 e in\u00edcio da d\u00e9cada de 1990.<\/p><p><strong>Escopo de exposi\u00e7\u00f5es<\/strong><\/p><p>1. Inteligente fabrica\u00e7\u00e3o de s\u00e9rie falange\uff1a<br \/>1. Digital, em rede, inteligente e fabrica\u00e7\u00e3o de sistemas e solu\u00e7\u00f5es (CNC dispositivos e unidades digitais, oficinas, inteligente f\u00e1brica de equipamentos e sistemas)<br \/>2. Rob\u00f4s industriais e sistemas de controle de automa\u00e7\u00e3o (DCS, PLC, IPC)<br \/>3. Avan\u00e7adas de automa\u00e7\u00e3o industrial instrumentos (temperatura, press\u00e3o, vaz\u00e3o, n\u00edvel)<br \/>4. Fieldbus e industriais de comunica\u00e7\u00e3o de Internet e sistema de seguran\u00e7a<br \/>5. High-end de precis\u00e3o m\u00e1quinas e equipamentos<br \/>6. Sensores e sistemas de rede de sensores sem fio<br \/>7. Controle inteligente de v\u00e1lvula e do atuador<br \/>8. Sistema de controle Industrial da informa\u00e7\u00e3o e tecnologia de seguran\u00e7a de rede e equipamentos de servi\u00e7o<\/p><p>2. Falange de modernos instrumentos cient\u00edficos\uff1a<br \/>1. V\u00e1rios instrumentos anal\u00edticos, instrumentos \u00f3ticos, instrumentos de laborat\u00f3rio e equipamentos<br \/>2. De medi\u00e7\u00e3o e instrumentos de teste<br \/>3. Perto do infravermelho a espectroscopia de tecnologia e equipamentos<br \/>4. Incorporado processamento digital de sinal do dispositivo<br \/>5. Geol\u00f3gica instrumentos, levantamento e mapeamento de instrumentos<br \/>6. Equipamento de teste para alimentos, rem\u00e9dios e produtos agr\u00edcolas<br \/>7. Eletr\u00f4nico de instrumentos de teste e instrumentos el\u00e9tricos<br \/>8. Instrumentos virtuais e software<\/p><p>3. Falange dos principais equipamentos m\u00e9dicos<br \/>1. De alto desempenho, de diagn\u00f3stico m\u00e9dico de equipamentos e instrumentos<br \/>2. Em grande escala de equipamentos de imagens m\u00e9dicas<br \/>3. Cl\u00ednico avan\u00e7ado de equipamentos de inspe\u00e7\u00e3o<br \/>4. Tratamento avan\u00e7ado de equipamentos e equipamentos<br \/>5. Equipamentos m\u00e9dicos e componentes<br \/>6. Saud\u00e1vel Internet das Coisas e pr\u00e1ticas, equipamento m\u00e9dico, equipamento m\u00e9dico port\u00e1til<\/p><p>Quarta, tecnol\u00f3gica falange de ind\u00fastrias emergentes estrat\u00e9gicas\uff1a<br \/>1. De energia nova ve\u00edculos (carros inteligentes, ve\u00edculos sem motorista)<br \/>2. A nova energia de baterias e dispositivos de fonte de alimenta\u00e7\u00e3o<br \/>3. Novos materiais<br \/>4. Micro-nano tecnologia e dispositivos<br \/>5. A impress\u00e3o 3D de equipamentos<br \/>6. Cidade Digital sistema e inteligente sistema de controle de tr\u00e1fego<br \/>7. Instrumentos meteorol\u00f3gicos, instrumentos mar\u00edtimos, espa\u00e7o e instrumentos<br \/>8. Energia Nuclear instrumenta\u00e7\u00e3o e controle de tecnologias e equipamentos de<br \/>9. O verde a ind\u00fastria de fabrica\u00e7\u00e3o de tecnologia e equipamentos (poupan\u00e7a de energia e protec\u00e7\u00e3o ambiental, de baixa emiss\u00e3o de carbono, reciclagem de res\u00edduos, tecnologia e equipamento)<br \/>10. Nacional de defesa da alto-tecnologia civil tecnologia e equipamentos<\/p><p>\u00a0<\/p><p><strong>Organizador<\/strong><br \/>A Sociedade chinesa de Instrumenta\u00e7\u00e3o<br \/>Organizador<br \/>Pequim Continente Hengke Desenvolvimento Do Com\u00e9rcio Co., Ltd.<\/p><p><br \/><strong>Informa\u00e7\u00f5es de contato<\/strong><\/p><p>MICONEX Equipe do Projeto<br \/>Endere\u00e7o: 23\u00ba Andar, Bloco A, Jinqiu Internacional de Constru\u00e7\u00e3o, N\u00ba 6 Zhichun Road, Haidian District, Beijing<br \/>telefone\uff1a+(8610) 8280 0630 8280 0621 8280 0975 8280 0773<br \/>Fax: +(8610) 8280 0857 8280 0731<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>DCL \u6b66\u6c49\u534e\u6613\u5c06\u53c2\u52a02023\u7b2c31\u5c4a\u4e2d\u56fd\u56fd\u9645\u6d4b\u91cf\u63a7\u5236\u4e0e\u4eea\u5668\u4eea\u8868\u5c55\u89c8\u4f1a\uff0c\u4e3a\u884c\u4e1a\u63d0\u4f9b\u7535\u52a8\u6267\u884c\u5668\u3001\u7535\u52a8\u9600\u95e8\u4ee5\u53ca\u7535\u52a8 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":6668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[333],"tags":[],"class_list":["post-6666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dcl-controls.com\/pt_pt\/wp-json\/wp\/v2\/posts\/6666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dcl-controls.com\/pt_pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dcl-controls.com\/pt_pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/pt_pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/pt_pt\/wp-json\/wp\/v2\/comments?post=6666"}],"version-history":[{"count":0,"href":"https:\/\/www.dcl-controls.com\/pt_pt\/wp-json\/wp\/v2\/posts\/6666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/pt_pt\/wp-json\/wp\/v2\/media\/6668"}],"wp:attachment":[{"href":"https:\/\/www.dcl-controls.com\/pt_pt\/wp-json\/wp\/v2\/media?parent=6666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dcl-controls.com\/pt_pt\/wp-json\/wp\/v2\/categories?post=6666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dcl-controls.com\/pt_pt\/wp-json\/wp\/v2\/tags?post=6666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}