{"id":6630,"date":"2023-10-07T15:17:04","date_gmt":"2023-10-07T07:17:04","guid":{"rendered":"https:\/\/www.dcl-controls.com\/?page_id=6630"},"modified":"2025-04-15T21:22:12","modified_gmt":"2025-04-15T13:22:12","slug":"applications","status":"publish","type":"page","link":"https:\/\/www.dcl-controls.com\/ja_jp\/solution\/applications","title":{"rendered":"DCL\u30a2\u30d7\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u9818\u57df"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6630\" class=\"elementor elementor-6630\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09eff24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09eff24\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b70b0dd\" data-id=\"b70b0dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-503ef3d elementor-widget elementor-widget-heading\" data-id=\"503ef3d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DCL\u30a2\u30d7\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u9818\u57df<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5639f4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d5639f4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c88245f\" data-id=\"c88245f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e852ff9 elementor-widget elementor-widget-heading\" data-id=\"e852ff9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u7a7a\u8abf<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6ec524 elementor-widget elementor-widget-template\" data-id=\"d6ec524\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10241\" class=\"elementor elementor-10241\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-661d20e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"661d20e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b294c46\" data-id=\"b294c46\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30f1dd9 elementor-widget elementor-widget-text-editor\" data-id=\"30f1dd9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u51b7\u51cd\u6a5f<\/li><li>\u51b7\u5374\u6c34-\u51b7\u6c34\u5faa\u74b0\u30b7\u30b9\u30c6\u30e0<\/li><li>\u51b7\u5374\u5854<\/li><li>\u63db\u6c17\u5de5\u5b66<\/li><li>\u52a0\u71b1\u30b7\u30b9\u30c6\u30e0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ad454ac\" data-id=\"ad454ac\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d284dc6 elementor-widget elementor-widget-image\" data-id=\"d284dc6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"678\" height=\"453\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/hvac\/dcl-in-hvac.webp\" class=\"attachment-full size-full wp-image-6573\" alt=\"\u534e\u6613DCL\u7535\u52a8\u6267\u884c\u5668\u5728\u6696\u901a\u7a7a\u8c03\u9886\u57df\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/hvac\/dcl-in-hvac.webp 678w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/hvac\/dcl-in-hvac-18x12.webp 18w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f6658a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3f6658a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-050023d\" data-id=\"050023d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fec5d0 elementor-widget elementor-widget-image\" data-id=\"5fec5d0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"578\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/home\/images\/routers\/dcl-gree-water-cooled-centrifugal-chillers.webp\" class=\"attachment-full size-full wp-image-4833\" alt=\"DCL \u534e\u6613\u667a\u63a7 \u5de5\u4e1a\u5236\u51b7 \u5e94\u7528\u573a\u666f | Water Cooled Centrifugal Chiller\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/home\/images\/routers\/dcl-gree-water-cooled-centrifugal-chillers.webp 500w, https:\/\/www.dcl-controls.com\/content\/dam\/home\/images\/routers\/dcl-gree-water-cooled-centrifugal-chillers-260x300.webp 260w, https:\/\/www.dcl-controls.com\/content\/dam\/home\/images\/routers\/dcl-gree-water-cooled-centrifugal-chillers-10x12.webp 10w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ab1fe8 elementor-widget elementor-widget-heading\" data-id=\"6ab1fe8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u30ac\u30a4\u30c9\u30d9\u30fc\u30f3\u30d0\u30a4\u30d1\u30b9\u30d0\u30eb\u30d6<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b52a38c elementor-widget elementor-widget-heading\" data-id=\"b52a38c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u51b7\u51cd\u6a5f<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-23f6a6a\" data-id=\"23f6a6a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-528eb62 elementor-widget elementor-widget-image\" data-id=\"528eb62\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"578\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/hvac\/dcl-in-chilled-water-circulation.webp\" class=\"attachment-full size-full wp-image-6574\" alt=\"DCL\u7535\u52a8\u6267\u884c\u5668\u5728\u51b7\u5374\u6c34\u5faa\u73af\u548c\u51b7\u51bb\u6c34\u5faa\u73af\u4e2d\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/hvac\/dcl-in-chilled-water-circulation.webp 500w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/hvac\/dcl-in-chilled-water-circulation-10x12.webp 10w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-843700f elementor-widget elementor-widget-heading\" data-id=\"843700f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u8abf\u6574\u5f01<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24532a8 elementor-widget elementor-widget-heading\" data-id=\"24532a8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u51b7\u5374\u6c34-\u51b7\u6c34\u5faa\u74b0\u30b7\u30b9\u30c6\u30e0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eb5a9f4\" data-id=\"eb5a9f4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-878efd2 elementor-widget elementor-widget-image\" data-id=\"878efd2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/hvac\/dcl-in-ventilation2.webp\" class=\"attachment-full size-full wp-image-6576\" alt=\"DCL\u7535\u52a8\u6267\u884c\u5668\u5728\u901a\u98ce\u7cfb\u7edf\u4e2d\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/hvac\/dcl-in-ventilation2.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/hvac\/dcl-in-ventilation2-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c35a950 elementor-widget elementor-widget-heading\" data-id=\"c35a950\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u30c0\u30f3\u30d1\u30fc\u30a2\u30af\u30c1\u30e5\u30a8\u30fc\u30bf<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d560836 elementor-widget elementor-widget-heading\" data-id=\"d560836\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u63db\u6c17\u5de5\u5b66<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d70513 elementor-widget elementor-widget-text-editor\" data-id=\"4d70513\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"\/ja_jp\/solution\/applications\/hvac\/\">\u8a73\u7d30\u306f\u3053\u3061\u3089\uff1e<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-159375f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"159375f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f4e5a6\" data-id=\"2f4e5a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b752ab1 elementor-widget elementor-widget-heading\" data-id=\"b752ab1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u96fb\u6c17<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fb3a64 elementor-widget elementor-widget-template\" data-id=\"1fb3a64\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10245\" class=\"elementor elementor-10245\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb47392 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cb47392\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aeadb84\" data-id=\"aeadb84\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8970152 elementor-widget elementor-widget-text-editor\" data-id=\"8970152\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u98a8\u529b\u767a\u96fb\u7ffc\u5468\u308a\u306e\u6f64\u6ed1\u3001\u51b7\u5374\u30b7\u30b9\u30c6\u30e0<\/li><li>\u30c0\u30f3\u30d1\u30fc\u7528\u30a8\u30a2\u30fc\u4f9b\u7d66\u30b7\u30b9\u30c6\u30e0\u306e\u71b1\u96fb\u767a\u96fb\u30e6\u30cb\u30c3\u30c8<\/li><li>\u6392\u30ac\u30b9\u5236\u5fa1\u30d0\u30eb\u30d6\u306e\u305f\u3081\u306e\u71b1\u96fb\u767a\u96fb\u30e6\u30cb\u30c3\u30c8<\/li><li>\u74b0\u5883\u4fdd\u8b77\u8a2d\u5099<\/li><li>\u539f\u5b50\u529b\u767a\u96fb\u6240<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a2790b6\" data-id=\"a2790b6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a4b4a1 elementor-widget elementor-widget-image\" data-id=\"4a4b4a1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/power\/dcl-used-in-wind-power.webp\" class=\"attachment-full size-full wp-image-6578\" alt=\"\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/power\/dcl-used-in-wind-power.webp 1024w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/power\/dcl-used-in-wind-power-18x12.webp 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35c0596 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"35c0596\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2cac2c5\" data-id=\"2cac2c5\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-236b855 elementor-widget elementor-widget-image\" data-id=\"236b855\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/power\/dcl-used-in-wind-mill.webp\" class=\"attachment-full size-full wp-image-6577\" alt=\"DCL\u7535\u52a8\u6267\u884c\u5668\u5728\u98ce\u7535\u884c\u4e1a\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/power\/dcl-used-in-wind-mill.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/power\/dcl-used-in-wind-mill-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c269c68 elementor-widget elementor-widget-heading\" data-id=\"c269c68\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u6e29\u5ea6\u8abf\u6574\u5f01<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a45fec elementor-widget elementor-widget-heading\" data-id=\"6a45fec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u98a8\u529b\u767a\u96fb\u7ffc\u5468\u308a\u306e\u6f64\u6ed1\u3001\u51b7\u5374\u30b7\u30b9\u30c6\u30e0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7a256b7\" data-id=\"7a256b7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9abb3b elementor-widget elementor-widget-image\" data-id=\"a9abb3b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"578\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/cases\/nuclear-power.webp\" class=\"attachment-full size-full wp-image-5996\" alt=\"DCL\u6267\u884c\u5668\u7528\u4e8e\u6838\u7535\u7ad9 | DCL Actuator in Nuclear Power Station\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/cases\/nuclear-power.webp 500w, https:\/\/www.dcl-controls.com\/content\/dam\/cases\/nuclear-power-10x12.webp 10w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64ffbab elementor-widget elementor-widget-heading\" data-id=\"64ffbab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u51b7\u5374\u6c34\u5faa\u74b0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a325675 elementor-widget elementor-widget-heading\" data-id=\"a325675\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u539f\u5b50\u529b\u767a\u96fb<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2cd0581\" data-id=\"2cd0581\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15d6cdc elementor-widget elementor-widget-image\" data-id=\"15d6cdc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/power\/dcl-used-in-geothermal-power.webp\" class=\"attachment-full size-full wp-image-6623\" alt=\"DCL\u6267\u884c\u5668\u5728\u5730\u70ed\u53d1\u7535\u7ad9\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/power\/dcl-used-in-geothermal-power.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/power\/dcl-used-in-geothermal-power-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04b112b elementor-widget elementor-widget-heading\" data-id=\"04b112b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u71b1\u30b5\u30a4\u30af\u30ea\u30f3\u30b0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06001ab elementor-widget elementor-widget-heading\" data-id=\"06001ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u5730\u71b1\u767a\u96fb<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4623217 elementor-widget elementor-widget-text-editor\" data-id=\"4623217\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"\/ja_jp\/solution\/applications\/power\/\">\u8a73\u7d30\u306f\u3053\u3061\u3089\uff1e<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-917115c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"917115c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c955d42\" data-id=\"c955d42\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5346aa1 elementor-widget elementor-widget-heading\" data-id=\"5346aa1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u6c34<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04c40f5 elementor-widget elementor-widget-template\" data-id=\"04c40f5\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10249\" class=\"elementor elementor-10249\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91ef47c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"91ef47c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4c3e8d6\" data-id=\"4c3e8d6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a6d74f elementor-widget elementor-widget-text-editor\" data-id=\"9a6d74f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u6d44\u6c34\u51e6\u7406\u88c5\u7f6e<\/li><li>\u6d77\u6c34\u6de1\u6c34\u5316\u88c5\u7f6e<\/li><li>Waterwater<\/li><li>\u4e0b\u6c34\u51e6\u7406\u5834<\/li><li>\u7523\u696d\u6392\u6c34\u51e6\u7406<\/li><li style=\"font-size: 18px;\">\u592a\u967d\u5149\u81ea\u52d54G\u6c34\u30d0\u30eb\u30d6<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e10782d\" data-id=\"e10782d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-901ff32 elementor-widget elementor-widget-image\" data-id=\"901ff32\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"635\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-water-2.webp\" class=\"attachment-full size-full wp-image-6625\" alt=\"DCL\u6267\u884c\u5668\u5728\u6c34\u5904\u7406\u9886\u57df\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-water-2.webp 1000w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-water-2-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-006febf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"006febf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0bfde3f\" data-id=\"0bfde3f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0625d2f elementor-widget elementor-widget-image\" data-id=\"0625d2f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-water-purify.webp\" class=\"attachment-full size-full wp-image-6624\" alt=\"\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-water-purify.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-water-purify-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdeecb8 elementor-widget elementor-widget-heading\" data-id=\"fdeecb8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u5236\u5fa1\u30d0\u30eb\u30d6<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-790b101 elementor-widget elementor-widget-heading\" data-id=\"790b101\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u6d44\u6c34\u51e6\u7406<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c043601\" data-id=\"c043601\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b4733a elementor-widget elementor-widget-image\" data-id=\"3b4733a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-water-supply.webp\" class=\"attachment-full size-full wp-image-6626\" alt=\"DCL\u6267\u884c\u5668\u5728\u81ea\u6765\u6c34\u5382\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-water-supply.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-water-supply-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dff090 elementor-widget elementor-widget-heading\" data-id=\"6dff090\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u30d5\u30e9\u30c3\u30b7\u30f3\u30b0\u30d0\u30eb\u30d6\u6e05\u6c34\u30d0\u30eb\u30d6<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8244025 elementor-widget elementor-widget-heading\" data-id=\"8244025\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Waterwater<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-95fce54\" data-id=\"95fce54\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c710cc6 elementor-widget elementor-widget-image\" data-id=\"c710cc6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-wastewater-treatment.webp\" class=\"attachment-full size-full wp-image-6581\" alt=\"DCL\u6267\u884c\u5668\u5728\u6c61\u6c34\u5904\u7406\u5382\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-wastewater-treatment.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/water\/dcl-actuator-used-in-wastewater-treatment-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-198ed8b elementor-widget elementor-widget-heading\" data-id=\"198ed8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u5236\u5fa1\u30d0\u30eb\u30d6<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07c95e3 elementor-widget elementor-widget-heading\" data-id=\"07c95e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u4e0b\u6c34\u51e6\u7406\u5834<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7decc40 elementor-widget elementor-widget-text-editor\" data-id=\"7decc40\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"\/ja_jp\/solution\/applications\/water\/\">\u8a73\u7d30\u306f\u3053\u3061\u3089\uff1e<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b193845 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b193845\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3baa40e\" data-id=\"3baa40e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-080d050 elementor-widget elementor-widget-heading\" data-id=\"080d050\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u51b6\u91d1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d0ae15 elementor-widget elementor-widget-template\" data-id=\"6d0ae15\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10254\" class=\"elementor elementor-10254\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e35237 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3e35237\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78a8261\" data-id=\"78a8261\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f9bf06 elementor-widget elementor-widget-text-editor\" data-id=\"7f9bf06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u30a8\u30a2\u30d0\u30eb\u30d6\u30d0\u30c3\u30d5\u30eb<\/li><li>\u6392\u30ac\u30b9\u30d1\u30a4\u30d7\u30e9\u30a4\u30f3<\/li><li>\u51b7\u5374\u5854<\/li><li>\u71c3\u6c14\u7ba1\u9053<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fbe9080\" data-id=\"fbe9080\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ffe5dd elementor-widget elementor-widget-image\" data-id=\"4ffe5dd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"682\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/metallurgy.webp\" class=\"attachment-full size-full wp-image-6659\" alt=\"DCL\u6267\u884c\u5668\u5728\u51b6\u91d1\u884c\u4e1a\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/metallurgy.webp 1000w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/metallurgy-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eee2c72 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"eee2c72\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f4ffaef\" data-id=\"f4ffaef\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7181a65 elementor-widget elementor-widget-image\" data-id=\"7181a65\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/damp-in-metallurgy.webp\" class=\"attachment-full size-full wp-image-6660\" alt=\"DCL\u6267\u884c\u5668\u5728\u51b6\u91d1\u884c\u4e1a\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/damp-in-metallurgy.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/damp-in-metallurgy-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f69c71a elementor-widget elementor-widget-heading\" data-id=\"f69c71a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u30c0\u30f3\u30d1\u30fc\u30d0\u30c3\u30d5\u30eb<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-467ca10 elementor-widget elementor-widget-heading\" data-id=\"467ca10\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u6392\u30ac\u30b9\u51e6\u7406<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5b654dd\" data-id=\"5b654dd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98062cd elementor-widget elementor-widget-image\" data-id=\"98062cd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/cool-tower.webp\" class=\"attachment-full size-full wp-image-6853\" alt=\"DCL\u5728\u51b6\u91d1\u884c\u4e1a\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/cool-tower.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/cool-tower-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ed553b elementor-widget elementor-widget-heading\" data-id=\"9ed553b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u51b7\u5374\u6c34\u5236\u5fa1\u30d0\u30eb\u30d6<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5d0081 elementor-widget elementor-widget-heading\" data-id=\"d5d0081\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u51b7\u5374\u5854<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ee73a8f\" data-id=\"ee73a8f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bb963a elementor-widget elementor-widget-image\" data-id=\"0bb963a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/flue-gas-pipe.webp\" class=\"attachment-full size-full wp-image-6854\" alt=\"\u6b66\u6c49\u534e\u6613\u5728\u51b6\u91d1\u884c\u4e1a\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/flue-gas-pipe.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/metallurgy\/flue-gas-pipe-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83f48b7 elementor-widget elementor-widget-heading\" data-id=\"83f48b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u6392\u6c17\u30d0\u30eb\u30d6<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-499065b elementor-widget elementor-widget-heading\" data-id=\"499065b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u6392\u30ac\u30b9\u30d1\u30a4\u30d7\u30e9\u30a4\u30f3<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-649c01b elementor-widget elementor-widget-text-editor\" data-id=\"649c01b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"\/ja_jp\/solution\/applications\/\">\u8a73\u7d30\u306f\u3053\u3061\u3089\uff1e<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e09749d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e09749d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9da2410\" data-id=\"9da2410\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8f4d3a elementor-widget elementor-widget-heading\" data-id=\"a8f4d3a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u305d\u306e\u4ed6\u306e\u7523\u696d\u30d7\u30ed\u30bb\u30b9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15c2ca2 elementor-widget elementor-widget-template\" data-id=\"15c2ca2\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10259\" class=\"elementor elementor-10259\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b08c9a9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b08c9a9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4da5e42\" data-id=\"4da5e42\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1d7d98 elementor-widget elementor-widget-text-editor\" data-id=\"f1d7d98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>\u7a92\u7d20\u767a\u751f\u88c5\u7f6e<\/li>\n<li>\u7523\u696d\u7528\u30d0\u30fc\u30ca\u30fc<\/li>\n<li>\u6db2\u4f53\u51b7\u5374\u30b7\u30b9\u30c6\u30e0<\/li><li>\u6d88\u9632\u653e\u6c34\u9283<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ba33e4d\" data-id=\"ba33e4d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bb39a1 elementor-widget elementor-widget-image\" data-id=\"7bb39a1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"644\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/industrial-process-3.webp\" class=\"attachment-full size-full wp-image-6655\" alt=\"DCL\u6267\u884c\u5668\u5728\u5de5\u4e1a\u8fc7\u7a0b\u63a7\u5236\u4e2d\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/industrial-process-3.webp 1000w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/industrial-process-3-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2596af1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2596af1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e2658bd\" data-id=\"e2658bd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70f496e elementor-widget elementor-widget-image\" data-id=\"70f496e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/carriage-data-center.webp\" class=\"attachment-full size-full wp-image-6654\" alt=\"DCL\u6267\u884c\u5668\u5728\u96c6\u88c5\u7bb1\u6570\u636e\u4e2d\u5fc3\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/carriage-data-center.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/carriage-data-center-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88f6792 elementor-widget elementor-widget-heading\" data-id=\"88f6792\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u6db2\u4f53\u51b7\u5374\u30b7\u30b9\u30c6\u30e0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a46e07a elementor-widget elementor-widget-heading\" data-id=\"a46e07a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u30b3\u30f3\u30c6\u30ca\u30c7\u30fc\u30bf\u30bb\u30f3\u30bf\u30fc<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cf12574\" data-id=\"cf12574\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d50dc90 elementor-widget elementor-widget-image\" data-id=\"d50dc90\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"578\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/cases\/nitrogen-generator.webp\" class=\"attachment-full size-full wp-image-5994\" alt=\"\u5236\u6c2e\u673a | Nitrogen Generator\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/cases\/nitrogen-generator.webp 500w, https:\/\/www.dcl-controls.com\/content\/dam\/cases\/nitrogen-generator-10x12.webp 10w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-652fcc0 elementor-widget elementor-widget-heading\" data-id=\"652fcc0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u8abf\u6574\u5f01<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f6769a elementor-widget elementor-widget-heading\" data-id=\"0f6769a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u7a92\u7d20\u767a\u751f\u88c5\u7f6e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c5f24cd\" data-id=\"c5f24cd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5100a85 elementor-widget elementor-widget-image\" data-id=\"5100a85\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/burner.webp\" class=\"attachment-full size-full wp-image-6653\" alt=\"DCL\u6267\u884c\u5668\u5728\u5de5\u4e1a\u71c3\u70e7\u5668\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/burner.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/burner-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04009e5 elementor-widget elementor-widget-heading\" data-id=\"04009e5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u5438\u6c17\u30d0\u30eb\u30d6\u30d7\u30ec\u30fc\u30c8<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c80f33 elementor-widget elementor-widget-heading\" data-id=\"8c80f33\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u7523\u696d\u7528\u30d0\u30fc\u30ca\u30fc<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a99bbac elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a99bbac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5138a03\" data-id=\"5138a03\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46429b2 elementor-widget elementor-widget-image\" data-id=\"46429b2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"690\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/fire-water-monitor.webp\" class=\"attachment-full size-full wp-image-6858\" alt=\"\u6b66\u6c49\u534e\u6613DCL\u5728\u6d88\u9632\u7684\u5e94\u7528\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/fire-water-monitor.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/applications\/images\/others\/fire-water-monitor-10x12.webp 10w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-568d950 elementor-widget elementor-widget-heading\" data-id=\"568d950\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u6c34\u30d0\u30eb\u30d6<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a657f54 elementor-widget elementor-widget-heading\" data-id=\"a657f54\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u6d88\u9632\u653e\u6c34\u9283<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d35ef46\" data-id=\"d35ef46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0d52014\" data-id=\"0d52014\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e42377 elementor-widget elementor-widget-text-editor\" data-id=\"6e42377\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"\/ja_jp\/solution\/applications\/industrial-process\/\">\u8a73\u7d30\u306f\u3053\u3061\u3089\uff1e<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>DCL\u5e94\u7528\u9886\u57df \u6696\u901a\u7a7a\u8c03 \u67e5\u770b\u66f4\u591a &gt; \u7535\u529b \u67e5\u770b\u66f4\u591a &gt; \u6c34\u52a1 \u67e5\u770b\u66f4\u591a &gt; \u51b6\u91d1 \u67e5\u770b\u66f4\u591a &gt; \u5176\u5b83\u5de5\u4e1a\u8fc7\u7a0b \u67e5\u770b\u66f4\u591a &gt;<\/p>","protected":false},"author":1,"featured_media":7371,"parent":5967,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6630","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"rankMath":{"parentDomain":"dcl-controls.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":true,"featuredImageNotice":"Facebook \u306a\u3069\u306e\u30bd\u30fc\u30b7\u30e3\u30eb\u30e1\u30c7\u30a3\u30a2\u30b5\u30a4\u30c8\u3067\u4f7f\u308f\u308c\u308b\u3088\u3046\u306b\u3059\u308b\u306b\u306f\u3001\u753b\u50cf\u30b5\u30a4\u30ba\u3092200x200\u30d4\u30af\u30bb\u30eb\u4ee5\u4e0a\u306b\u3059\u308b\u3079\u304d\u3067\u3059\u3002","pluginReviewed":true,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"applications","permalinkFormat":"https:\/\/www.dcl-controls.com\/ja_jp\/solution\/%pagename%","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/www.dcl-controls.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"\u6b66\u6c49\u534e\u6613\u7684DCL\u7cfb\u5217\u6267\u884c\u5668\u548c\u534e\u6613\u667a\u63a7\u7cfb\u5217\u6d41\u63a7\u4ea7\u54c1\u5e7f\u6cdb\u5e94\u7528\u4e8e\u5de5\u4e1a\u8fc7\u7a0b\u4e2d\u7684\u6d41\u4f53\u63a7\u5236\uff0c\u5305\u62ec\uff1a\u6c34\u52a1\u3001\u77ff\u4e1a\u3001\u51b6\u91d1\u3001\u77f3\u6cb9\u3001\u5316\u5de5\u3001\u80fd\u6e90\u3001\u73af\u4fdd\u3001\u8239\u8236\u3001\u6696\u901a\u3001\u697c\u5b87\u81ea\u52a8\u5316\u7b49\u4f17\u591a\u884c\u4e1a\u3002 \u5386\u7ecf22\u5e74\uff0cDCL\u5e94\u7528\u9886\u57df\u548c\u534e\u6613\u667a\u63a7\u5e94\u7528\u9886\u57df\u7684\u4ea7\u54c1\u53ca\u65b9\u6848\u5728\u884c\u4e1a\u5185\u7d2f\u79ef\u4e86\u975e\u5e38\u591a\u7684\u6210\u529f\u6848\u4f8b\u3002\u8fd9\u4e9b\u6848\u4f8b\u8bc1\u660e\uff1aDCL\u662f\u53ef\u9760\u8010\u7528\u7684\uff0c\u662f\u503c\u5f97\u5ba2\u6237\u4fe1\u8d56\u7684\u3002 \u4eca\u5929\uff0cDCL \u534e\u6613\u667a\u63a7 \u5c06\u7ee7\u7eed\u81f4\u529b\u4e8e\u4e3a\u60a8\u63d0\u4f9b\u4e13\u4e1a\u53ef\u9760\u7684\u89e3\u51b3\u65b9\u6848\u3002","focusKeywords":"DCL\u5e94\u7528\u9886\u57df","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"\u30e6\u30fc\u30b6\u30fc\u540d","primaryTerm":0,"authorName":"DCL \u534e\u6613\u667a\u63a7","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["\u3059\u3054\u3044","\u611f\u52d5","\u9a5a\u304f","\u552f\u4e00\u7121\u4e8c","\u7f8e\u3057\u3044","\u5e78\u798f","\u8f1d\u304b\u3057\u3044","\u9b45\u60d1\u7684","\u30ab\u30ea\u30b9\u30de\u7684","\u885d\u6483","\u660e\u77ad","\u5b8c\u5168\u306b","\u4fe1\u983c\u3067\u304d\u308b","\u81ea\u4fe1","\u91cd\u8981","\u5275\u9020\u7684","\u6c7a\u5b9a\u7684\u306b","\u7f8e\u5473\u3057\u3044","\u8a3c\u660e\u3059\u308b","\u6025\u3044\u3067","\u6c7a\u610f","\u4fa1\u5024\u304c\u3042\u308b","\u30c0\u30a4\u30ca\u30df\u30c3\u30af","\u611f\u52d5\u7684","\u4e0d\u53ef\u6b20","\u30a4\u30f3\u30b9\u30d4\u30ec\u30fc\u30b7\u30e7\u30f3","\u9769\u65b0\u7684","\u5f37\u529b\u306a","\u9b54\u6cd5\u306e\u3088\u3046\u306a","\u58ee\u5927","\u6b74\u53f2\u7684","\u91cd\u8981\u306a","\u4fe1\u3058\u3089\u308c\u306a\u3044","\u7d76\u5bfe\u5fc5\u8981","\u5fd8\u308c\u3089\u308c\u306a\u3044","\u9b45\u529b\u7684","\u523a\u6fc0\u7684","\u52b9\u679c\u7684","\u9769\u547d\u7684","\u6210\u529f","\u559c\u3073","\u5b89\u5168","\u611f\u52d5\u7684","\u6e80\u3061\u8db3\u308a\u305f","\u7d20\u6674\u3089\u3057\u3044","\u72ec\u7279","\u4fa1\u5024\u304c\u3042\u308b","\u7d20\u6674\u3089\u3057\u3044","\u71b1\u5fc3\u306a","\u52dd\u5229","\u6d3b\u6c17\u3065\u3051\u308b","\u771f\u306b","\u60c5\u71b1\u7684","\u71b1\u5fc3\u306a","\u512a\u96c5","\u5927\u80c6","\u7406\u60f3\u7684","\u4fe1\u3058\u3089\u308c\u306a\u3044\u307b\u3069","\u73fe\u5b9f\u7684","\u6700\u9069","\u4e26\u5916\u308c\u305f","\u8c4a\u5bcc","\u58ee\u89b3","\u5922\u306e\u3088\u3046\u306a","\u611f\u6fc0","\u9b45\u4e86\u3059\u308b","\u5b8c\u74a7","\u58ee\u5927","\u8c6a\u83ef","\u9a5a\u7570\u7684","\u610f\u6b32\u7684","\u71b1\u72c2\u7684","\u753b\u671f\u7684","\u5f37\u70c8","\u9a5a\u6115","\u7dca\u6025","\u89e3\u6c7a","\u6700\u9ad8","\u8c4a\u304b","\u5927\u80c6\u4e0d\u6575","\u6709\u540d","\u611b\u3055\u308c\u308b","\u7279\u5225","\u4fe1\u3058\u3089\u308c\u308b","\u78ba\u5b9f","\u60c5\u71b1","\u671f\u5f85","\u6700\u524d\u7dda","\u958b\u62d3\u8005","\u30d1\u30ef\u30d5\u30eb","\u5f71\u97ff\u529b","\u9ad8\u54c1\u8cea","\u5049\u5927","\u7c21\u5358","\u5b89\u5fc3","\u91cd\u8981","\u72ec\u81ea","\u6804\u5149","\u7121\u6575","\u81ea\u7531","\u5e0c\u671b","\u5947\u8de1","\u6210\u529f","\u8c4a\u304b\u306a","\u529b\u5f37\u3044","\u6804\u5149","\u98db\u8e8d","\u6ce8\u76ee","\u58ee\u5927","\u6311\u6226\u7684","\u4f1d\u8aac","\u7121\u6575","\u83ef\u9e97","\u9a5a\u7570","\u7d20\u6674\u3089\u3057\u3044","\u58ee\u9e97","\u5049\u5927\u306a","\u5049\u5927","\u4f1d\u8aac\u7684","\u523a\u6fc0\u7684","\u30a8\u30ad\u30b5\u30a4\u30c6\u30a3\u30f3\u30b0","\u671f\u5f85","\u61a7\u308c","\u512a\u79c0","\u7d76\u5bfe","\u5927\u6210\u529f","\u60f3\u50cf\u3092\u7d76\u3059\u308b","\u5b8c\u74a7","\u9b45\u529b\u7684","\u611f\u52d5\u7684","\u5049\u5927","\u512a\u96c5","\u7d20\u6674\u3089\u3057\u3044","\u9769\u65b0\u7684","\u5727\u5012\u7684","\u552f\u4e00"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":true},"homeUrl":"https:\/\/www.dcl-controls.com\/ja_jp\/","objectID":6630,"objectType":"post","locale":"ja","localeFull":"ja","overlayImages":{"play":{"name":"Play \u30a2\u30a4\u30b3\u30f3","url":"https:\/\/www.dcl-controls.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/usr\/share\/nginx\/html\/dcl-controls.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF \u30a2\u30a4\u30b3\u30f3","url":"https:\/\/www.dcl-controls.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/usr\/share\/nginx\/html\/dcl-controls.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/www.dcl-controls.com\/content\/dam\/home\/images\/shelf-banner\/dcl-actuator-product-line.webp","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fwww.dcl-controls.com%2Fja_jp%2F&r=https%3A%2F%2Fwww.dcl-controls.com%2Fja_jp%2Fwp-json%2Fwp%2Fv2%2Fpages%2F6630%3Fnonce%3D676f256df6","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/www.dcl-controls.com\/content\/dam\/site\/cropped-dcl-logo-square-512-2-32x32.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"\u30a2\u30c3\u30d7\u30b0\u30ec\u30fc\u30c9","trendsPreviewImage":"https:\/\/www.dcl-controls.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["\u3059\u3054\u3044","\u611f\u52d5","\u9a5a\u304f","\u552f\u4e00\u7121\u4e8c","\u7f8e\u3057\u3044","\u5e78\u798f","\u8f1d\u304b\u3057\u3044","\u9b45\u60d1\u7684","\u30ab\u30ea\u30b9\u30de\u7684","\u885d\u6483","\u660e\u77ad","\u5b8c\u5168\u306b","\u4fe1\u983c\u3067\u304d\u308b","\u81ea\u4fe1","\u91cd\u8981","\u5275\u9020\u7684","\u6c7a\u5b9a\u7684\u306b","\u7f8e\u5473\u3057\u3044","\u8a3c\u660e\u3059\u308b","\u6025\u3044\u3067","\u6c7a\u610f","\u4fa1\u5024\u304c\u3042\u308b","\u30c0\u30a4\u30ca\u30df\u30c3\u30af","\u611f\u52d5\u7684","\u4e0d\u53ef\u6b20","\u30a4\u30f3\u30b9\u30d4\u30ec\u30fc\u30b7\u30e7\u30f3","\u9769\u65b0\u7684","\u5f37\u529b\u306a","\u9b54\u6cd5\u306e\u3088\u3046\u306a","\u58ee\u5927","\u6b74\u53f2\u7684","\u91cd\u8981\u306a","\u4fe1\u3058\u3089\u308c\u306a\u3044","\u7d76\u5bfe\u5fc5\u8981","\u5fd8\u308c\u3089\u308c\u306a\u3044","\u9b45\u529b\u7684","\u523a\u6fc0\u7684","\u52b9\u679c\u7684","\u9769\u547d\u7684","\u6210\u529f","\u559c\u3073","\u5b89\u5168","\u611f\u52d5\u7684","\u6e80\u3061\u8db3\u308a\u305f","\u7d20\u6674\u3089\u3057\u3044","\u72ec\u7279","\u4fa1\u5024\u304c\u3042\u308b","\u7d20\u6674\u3089\u3057\u3044","\u71b1\u5fc3\u306a","\u52dd\u5229","\u6d3b\u6c17\u3065\u3051\u308b","\u771f\u306b","\u60c5\u71b1\u7684","\u71b1\u5fc3\u306a","\u512a\u96c5","\u5927\u80c6","\u7406\u60f3\u7684","\u4fe1\u3058\u3089\u308c\u306a\u3044\u307b\u3069","\u73fe\u5b9f\u7684","\u6700\u9069","\u4e26\u5916\u308c\u305f","\u8c4a\u5bcc","\u58ee\u89b3","\u5922\u306e\u3088\u3046\u306a","\u611f\u6fc0","\u9b45\u4e86\u3059\u308b","\u5b8c\u74a7","\u58ee\u5927","\u8c6a\u83ef","\u9a5a\u7570\u7684","\u610f\u6b32\u7684","\u71b1\u72c2\u7684","\u753b\u671f\u7684","\u5f37\u70c8","\u9a5a\u6115","\u7dca\u6025","\u89e3\u6c7a","\u6700\u9ad8","\u8c4a\u304b","\u5927\u80c6\u4e0d\u6575","\u6709\u540d","\u611b\u3055\u308c\u308b","\u7279\u5225","\u4fe1\u3058\u3089\u308c\u308b","\u78ba\u5b9f","\u60c5\u71b1","\u671f\u5f85","\u6700\u524d\u7dda","\u958b\u62d3\u8005","\u30d1\u30ef\u30d5\u30eb","\u5f71\u97ff\u529b","\u9ad8\u54c1\u8cea","\u5049\u5927","\u7c21\u5358","\u5b89\u5fc3","\u91cd\u8981","\u72ec\u81ea","\u6804\u5149","\u7121\u6575","\u81ea\u7531","\u5e0c\u671b","\u5947\u8de1","\u6210\u529f","\u8c4a\u304b\u306a","\u529b\u5f37\u3044","\u6804\u5149","\u98db\u8e8d","\u6ce8\u76ee","\u58ee\u5927","\u6311\u6226\u7684","\u4f1d\u8aac","\u7121\u6575","\u83ef\u9e97","\u9a5a\u7570","\u7d20\u6674\u3089\u3057\u3044","\u58ee\u9e97","\u5049\u5927\u306a","\u5049\u5927","\u4f1d\u8aac\u7684","\u523a\u6fc0\u7684","\u30a8\u30ad\u30b5\u30a4\u30c6\u30a3\u30f3\u30b0","\u671f\u5f85","\u61a7\u308c","\u512a\u79c0","\u7d76\u5bfe","\u5927\u6210\u529f","\u60f3\u50cf\u3092\u7d76\u3059\u308b","\u5b8c\u74a7","\u9b45\u529b\u7684","\u611f\u52d5\u7684","\u5049\u5927","\u512a\u96c5","\u7d20\u6674\u3089\u3057\u3044","\u9769\u65b0\u7684","\u5727\u5012\u7684","\u552f\u4e00"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"\u9996\u9875","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":["h1"],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/www.dcl-controls.com\/ja_jp\/wp-json\/wp\/v2\/pages\/6630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dcl-controls.com\/ja_jp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dcl-controls.com\/ja_jp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/ja_jp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/ja_jp\/wp-json\/wp\/v2\/comments?post=6630"}],"version-history":[{"count":0,"href":"https:\/\/www.dcl-controls.com\/ja_jp\/wp-json\/wp\/v2\/pages\/6630\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/ja_jp\/wp-json\/wp\/v2\/pages\/5967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/ja_jp\/wp-json\/wp\/v2\/media\/7371"}],"wp:attachment":[{"href":"https:\/\/www.dcl-controls.com\/ja_jp\/wp-json\/wp\/v2\/media?parent=6630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}