{"id":6793,"date":"2023-10-31T21:59:47","date_gmt":"2023-10-31T13:59:47","guid":{"rendered":"https:\/\/www.dcl-controls.com\/?page_id=6793"},"modified":"2024-11-12T11:20:22","modified_gmt":"2024-11-12T03:20:22","slug":"how-to-wire","status":"publish","type":"page","link":"https:\/\/www.dcl-controls.com\/es_es\/support\/actuators\/how-to-wire","title":{"rendered":"C\u00f3mo instalar el cable del actuador el\u00e9ctrico?"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6793\" class=\"elementor elementor-6793\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2bdb9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2bdb9a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0464bce\" data-id=\"0464bce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-844ac08 elementor-widget elementor-widget-image\" data-id=\"844ac08\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"617\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/dcl-how-to-wire.webp\" class=\"attachment-full size-full wp-image-6802\" alt=\"DCL\u7535\u52a8\u6267\u884c\u5668\u5982\u4f55\u63a5\u7ebf\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/dcl-how-to-wire.webp 800w, https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/dcl-how-to-wire-16x12.webp 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a78e355 elementor-widget elementor-widget-text-editor\" data-id=\"a78e355\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"text-decoration: underline;\"><a href=\"#1-2-way\">Elegir un solo canal o de doble canal m\u00e9todo de cableado<\/a><\/span><\/li><li><span style=\"text-decoration: underline;\"><a href=\"#wire-current\">Determinar la sobrecorriente de capacidad de los conductores de arn\u00e9s de cableado<\/a><\/span><\/li><li><span style=\"text-decoration: underline;\"><a href=\"#wire-diameter\">Elija el di\u00e1metro exterior del tubo del alambre<\/a><\/span><\/li><li><span style=\"text-decoration: underline;\"><a href=\"#sheild\">Elija si desea utilizar el blindaje<\/a><\/span><\/li><li><span style=\"text-decoration: underline;\"><a href=\"#downward\">Determinar la direcci\u00f3n del cable<\/a><\/span><\/li><li><span style=\"text-decoration: underline;\"><a href=\"#install\">instalar<\/a><\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73038cc elementor-widget elementor-widget-heading\" data-id=\"73038cc\" data-element_type=\"widget\" id=\"1-2-way\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. Elegir un solo canal o de doble canal m\u00e9todo de cableado<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4f9612 elementor-widget elementor-widget-image\" data-id=\"b4f9612\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"354\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/dcl-actuator-1-or-2-wire.webp\" class=\"attachment-full size-full wp-image-6801\" alt=\"DCL\u7535\u52a8\u6267\u884c\u5668\u5355\u8def\u3001\u53cc\u8def\u5e03\u7ebf\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/dcl-actuator-1-or-2-wire.webp 1200w, https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/dcl-actuator-1-or-2-wire-18x5.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2689b90 elementor-widget elementor-widget-text-editor\" data-id=\"2689b90\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0 \u00a0 \u00a0 El doble camino de cableado divide la l\u00ednea de alimentaci\u00f3n y la se\u00f1al el\u00e9ctrica d\u00e9bil l\u00ednea en dos grupos de cables, que est\u00e1n conectadas por separado. Este m\u00e9todo puede evitar el acoplamiento de interferencias de l\u00edneas el\u00e9ctricas de alta tensi\u00f3n a la debilidad de las se\u00f1ales el\u00e9ctricas de 4-20mA o 2-10V. Este acoplamiento ruta incluye la capacitancia y la inductancia par\u00e1sita entre los alambres. Es generalmente utilizado en el cableado de las situaciones de larga distancia, alta tensi\u00f3n, y el fuerte ruido de alta frecuencia.<\/p><p>\u00a0 \u00a0 \u00a0 Un solo canal de cableado sintetiza el cable de alimentaci\u00f3n y la d\u00e9bil se\u00f1al el\u00e9ctrica en un conjunto de cables y los rastros de ellos juntos. Es generalmente utilizado en el cableado situaciones donde la distancia est\u00e1 cerca, el voltaje de alimentaci\u00f3n es baja, y el ruido de alta frecuencia es d\u00e9bil.<\/p><ul><li>AC220V y AC380V ajustable actuadores el\u00e9ctricos, se recomienda el uso de un doble m\u00e9todo de cableado.<\/li><li>AC220V y AC380V actuadores el\u00e9ctricos con retroalimentaci\u00f3n de posici\u00f3n, se recomienda el uso de un doble m\u00e9todo de cableado.<\/li><li>Para DC24V y 24 v ca ajustable actuadores el\u00e9ctricos, de acuerdo con el ruido de alta frecuencia de la baja tensi\u00f3n de la l\u00ednea y la longitud del arn\u00e9s de cableado, elija el m\u00e9todo de cableado? (Se recomienda el uso de cableado doble)<\/li><li>Para DC24V y 24 v ca actuadores el\u00e9ctricos con retroalimentaci\u00f3n de posici\u00f3n, de acuerdo con el ruido de alta frecuencia de la baja tensi\u00f3n de la l\u00ednea y la longitud del arn\u00e9s de cableado, elija el m\u00e9todo de cableado? (Se recomienda el uso de cableado doble)<\/li><li>Para cambiar de tipo de actuadores el\u00e9ctricos que son conducidas directamente por las l\u00edneas de alimentaci\u00f3n, se recomienda el uso de un \u00fanico m\u00e9todo de cableado.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f9c28b elementor-widget elementor-widget-heading\" data-id=\"1f9c28b\" data-element_type=\"widget\" id=\"wire-current\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Determinar la sobrecorriente de capacidad de los conductores de arn\u00e9s de cableado<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-338764d elementor-widget elementor-widget-text-editor\" data-id=\"338764d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&nbsp; &nbsp; &nbsp; De acuerdo a la tensi\u00f3n nominal y la corriente nominal del actuador, seleccione el arn\u00e9s de cableado.<\/p>\n<p>&nbsp; &nbsp; &nbsp; <strong>consulta&nbsp;<span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); background-color: var(--ast-global-color-5);\">Tensi\u00f3n nominal y la corriente nominal\uff1a<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abd734d elementor-widget elementor-widget-toggle\" data-id=\"abd734d\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1801\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1801\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ordinario de la serie de actuadores el\u00e9ctricos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1801\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1801\"><p>\u00a0 \u00a0 <a href=\"\/es_es\/general-actuator-series\/dcl-05\/#char\" target=\"_blank\" rel=\"noopener\">DCL-05<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/general-actuator-series\/dcl-10\/#char\" target=\"_blank\" rel=\"noopener\">DCL-10<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/general-actuator-series\/dcl-20\/#char\" target=\"_blank\" rel=\"noopener\">DCL-20<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/general-actuator-series\/dcl-40\/#char\" target=\"_blank\" rel=\"noopener\">DCL-40<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/general-actuator-series\/dcl-60\/#char\" target=\"_blank\" rel=\"noopener\">DCL-60<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/general-actuator-series\/dcl-100\/#char\" target=\"_blank\" rel=\"noopener\">DCL-100<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/general-actuator-series\/dcl-160\/#char\" target=\"_blank\" rel=\"noopener\">DCL-160<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/general-actuator-series\/dcl-250\/#char\" target=\"_blank\" rel=\"noopener\">DCL-250<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1802\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1802\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">A prueba de explosi\u00f3n serie de actuadores el\u00e9ctricos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1802\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1802\"><p>\u00a0 \u00a0 <a href=\"\/es_es\/explosion-proof-actuator-series\/dcl-ex05\/#char\" target=\"_blank\" rel=\"noopener\">DCL-Ex05<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/explosion-proof-actuator-series\/dcl-ex10\/#char\" target=\"_blank\" rel=\"noopener\">DCL-Ex10<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/explosion-proof-actuator-series\/dcl-ex20\/#char\" target=\"_blank\" rel=\"noopener\">DCL-Ex20<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/explosion-proof-actuator-series\/dcl-ex40\/#char\" target=\"_blank\" rel=\"noopener\">DCL-Ex40<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/explosion-proof-actuator-series\/dcl-ex60\/#char\" target=\"_blank\" rel=\"noopener\">DCL-Ex60<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1803\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1803\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">R\u00e1pida apertura de la serie de actuadores el\u00e9ctricos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1803\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1803\"><p>\u00a0 \u00a0 <a href=\"\/es_es\/fast-move-actuator-series\/dcl-k05\/#char\" target=\"_blank\" rel=\"noopener\">DCL-K05<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/fast-move-actuator-series\/dcl-k10\/#char\" target=\"_blank\" rel=\"noopener\">DCL-K10<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/fast-move-actuator-series\/dcl-k20\/#char\" target=\"_blank\" rel=\"noopener\">DCL-K20<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/fast-move-actuator-series\/dcl-k40\/#char\" target=\"_blank\" rel=\"noopener\">DCL-K40<\/a><\/p><p>\u00a0 \u00a0 <a href=\"\/es_es\/fast-move-actuator-series\/dcl-k100\/#char\" target=\"_blank\" rel=\"noopener\">DCL-K100<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1804\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1804\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ultra-peque\u00f1o de la serie de actuadores el\u00e9ctricos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1804\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1804\"><p>\u00a0 \u00a0 <a href=\"#on-off-actuator\" target=\"_blank\" rel=\"noopener\">DCL-02<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c63f08e elementor-widget elementor-widget-heading\" data-id=\"c63f08e\" data-element_type=\"widget\" id=\"wire-diameter\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. Elija el di\u00e1metro exterior del tubo del alambre<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1872b72 elementor-widget elementor-widget-text-editor\" data-id=\"1872b72\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0 \u00a0 \u00a0 Con el fin de cumplir con los requisitos de rendimiento a prueba de agua, seleccione el di\u00e1metro exterior del tubo del alambre de acuerdo a la interfaz el\u00e9ctrica\uff1a<\/p><ul><li>G1\/2\uff1a\u22059 ~ \u220511<\/li><li>M20\u00d71.5\uff1a<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23f337e elementor-widget elementor-widget-heading\" data-id=\"23f337e\" data-element_type=\"widget\" id=\"shield\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. Elija si desea utilizar el blindaje<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b762f33 elementor-widget elementor-widget-image\" data-id=\"b762f33\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"321\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/dcl-shield-wire.webp\" class=\"attachment-full size-full wp-image-6803\" alt=\"DCL\u7535\u52a8\u6267\u884c\u5668\u5c4f\u853d\u7ebf\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/dcl-shield-wire.webp 600w, https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/dcl-shield-wire-18x10.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07d16fa elementor-widget elementor-widget-text-editor\" data-id=\"07d16fa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0 \u00a0 \u00a0 Cables apantallados puede proteger a los d\u00e9biles se\u00f1ales el\u00e9ctricas de ambiental, interferencias electromagn\u00e9ticas a trav\u00e9s de medidas de puesta a tierra. Se recomienda tomar las medidas de blindaje en la l\u00ednea de se\u00f1al\uff1a<\/p><ul><li>Para 4~20mA, se recomienda el uso de un cable blindado.<\/li><li>Para 2~10V, se recomienda el uso de cable blindado.<\/li><li>Para la posici\u00f3n de la resistencia de retroalimentaci\u00f3n de las se\u00f1ales, se recomienda el uso de cables apantallados.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6a15d0 elementor-widget elementor-widget-heading\" data-id=\"d6a15d0\" data-element_type=\"widget\" id=\"downward\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5. Determinar la direcci\u00f3n del cable<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfcd388 elementor-widget elementor-widget-text-editor\" data-id=\"dfcd388\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>En un entorno donde es posible que la lluvia o el agua se acumula a lo largo del cable, se recomienda que el cable extra\u00eddo de la interfaz el\u00e9ctrica del actuador el\u00e9ctrico que ir primero hacia abajo de modo que es inferior a la interfaz el\u00e9ctrica y, a continuaci\u00f3n, vaya a la batea. Esto evita que el agua estancada de penetrar en el mal sellado de la interfaz el\u00e9ctrica en el cable y causar da\u00f1o a la entrada de agua en el interior del actuador el\u00e9ctrico.<\/li><li>En el entorno de uso, donde la condensaci\u00f3n puede ocurrir, es recomendable para enrutar el cableado en la forma anterior para evitar la entrada de agua desde el actuador el\u00e9ctrico.<\/li><li>En el interior y otros lugares ventilados, actuadores el\u00e9ctricos no tienen requisitos especiales para el enrutamiento de los cables.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfb18f3 elementor-widget elementor-widget-image\" data-id=\"bfb18f3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"570\" src=\"https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/actuator-wire-direction.webp\" class=\"attachment-full size-full wp-image-6804\" alt=\"DCL\u7535\u52a8\u6267\u884c\u5668\u7ebf\u7f06\u65b9\u5411\" srcset=\"https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/actuator-wire-direction.webp 1200w, https:\/\/www.dcl-controls.com\/content\/dam\/support\/images\/actuator\/actuator-wire-direction-18x9.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5cbb1a elementor-widget elementor-widget-heading\" data-id=\"e5cbb1a\" data-element_type=\"widget\" id=\"install\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6. Conectar seg\u00fan el diagrama de cableado<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-017ecb3 elementor-widget elementor-widget-shortcode\" data-id=\"017ecb3\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">[astra_custom_layout id=4879]<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ceb833b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ceb833b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1921917\" data-id=\"1921917\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e03f3c9 elementor-widget elementor-widget-heading\" data-id=\"e03f3c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/es_es\/tech\/how-to-install-actuator\/\">Anterior: C\u00f3mo instalar el actuador a la v\u00e1lvula?<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9ab8cd5\" data-id=\"9ab8cd5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ba67c6 elementor-widget elementor-widget-heading\" data-id=\"4ba67c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/es_es\/tech\/set-up-dcl-valve\/\">Siguiente: C\u00f3mo configurar un interruptor de tipo el\u00e9ctrico de la v\u00e1lvula?<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u9009\u62e9\u5355\u8def\u6216\u53cc\u8def\u914d\u7ebf\u65b9\u5f0f \u786e\u5b9a\u5bfc\u7535\u7ebf\u675f\u7684\u8fc7\u6d41\u80fd\u529b \u9009\u62e9\u5408\u9002\u7684\u7ebf\u7ba1\u5916\u5f84 \u9009\u62e9\u662f\u5426\u4f7f\u7528\u5c4f\u853d \u786e\u5b9a\u7ebf\u7f06\u8d70\u5411 \u5b89\u88c5 1\u3001 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":6804,"parent":6673,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6793","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"rankMath":{"parentDomain":"dcl-controls.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":true,"featuredImageNotice":"La imagen destacada debe tener al menos 200 por 200 p\u00edxeles para que Facebook y otros sitios de redes sociales puedan escogerla.","pluginReviewed":true,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"how-to-wire","permalinkFormat":"https:\/\/www.dcl-controls.com\/es_es\/support\/actuators\/%pagename%","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/www.dcl-controls.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"\u5982\u4f55\u5b89\u88c5\u7535\u52a8\u6267\u884c\u5668\u7684\u7ebf\u675f\uff1f1\u3001\u9009\u62e9\u5355\u8def\u6216\u53cc\u8def\u914d\u7ebf\u65b9\u5f0f\u30022\u3001\u786e\u5b9a\u5bfc\u7535\u7ebf\u675f\u7684\u8fc7\u6d41\u80fd\u529b\u30023\u3001\u9009\u62e9\u5408\u9002\u7684\u7ebf\u7ba1\u5916\u5f84\u30024\u3001\u9009\u62e9\u662f\u5426\u4f7f\u7528\u5c4f\u853d\u30025\u3001\u786e\u5b9a\u7ebf\u675f\u8d70\u5411\u3002","focusKeywords":"\u5b89\u88c5\u7535\u52a8\u6267\u884c\u5668\u7684\u7ebf\u675f","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"nombre de usuario","primaryTerm":0,"authorName":"DCL \u534e\u6613\u667a\u63a7","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":true},"homeUrl":"https:\/\/www.dcl-controls.com\/es_es\/","objectID":6793,"objectType":"post","locale":"es","localeFull":"es_ES","overlayImages":{"play":{"name":"Icono de reproducci\u00f3n","url":"https:\/\/www.dcl-controls.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/usr\/share\/nginx\/html\/dcl-controls.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icono GIF","url":"https:\/\/www.dcl-controls.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/usr\/share\/nginx\/html\/dcl-controls.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/www.dcl-controls.com\/content\/dam\/home\/images\/shelf-banner\/dcl-actuator-product-line.webp","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fwww.dcl-controls.com%2Fes_es%2F&r=https%3A%2F%2Fwww.dcl-controls.com%2Fes_es%2Fwp-json%2Fwp%2Fv2%2Fpages%2F6793%3Fnonce%3D676f256df6","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/www.dcl-controls.com\/content\/dam\/site\/cropped-dcl-logo-square-512-2-32x32.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Actualizar","trendsPreviewImage":"https:\/\/www.dcl-controls.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"\u9996\u9875","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":["h1"],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/www.dcl-controls.com\/es_es\/wp-json\/wp\/v2\/pages\/6793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dcl-controls.com\/es_es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dcl-controls.com\/es_es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/es_es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/es_es\/wp-json\/wp\/v2\/comments?post=6793"}],"version-history":[{"count":0,"href":"https:\/\/www.dcl-controls.com\/es_es\/wp-json\/wp\/v2\/pages\/6793\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/es_es\/wp-json\/wp\/v2\/pages\/6673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dcl-controls.com\/es_es\/wp-json\/wp\/v2\/media\/6804"}],"wp:attachment":[{"href":"https:\/\/www.dcl-controls.com\/es_es\/wp-json\/wp\/v2\/media?parent=6793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}